{"id":30652,"date":"2022-08-15T15:57:54","date_gmt":"2022-08-15T13:57:54","guid":{"rendered":"https:\/\/avdmsolutions.ch\/?p=30652"},"modified":"2022-08-22T15:12:52","modified_gmt":"2022-08-22T13:12:52","slug":"imprimantes-primera-lx-3000","status":"publish","type":"post","link":"https:\/\/avdmsolutions.re\/en\/imprimantes-primera-lx-3000\/","title":{"rendered":"Imprimantes PRIMERA LX 3000"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; module_id=\u00a0\u00bb%91table id=2 \/%93&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb443.2px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1>Imprimante d&rsquo;\u00e9tiquettes couleur LX3000e<\/h1>\n<h2>Le tout nouveau syst\u00e8me Big Ink\u2122 permet de r\u00e9duire les co\u00fbts par \u00e9tiquette avec une vitesse et une qualit\u00e9 d&rsquo;impression exceptionnelles.<\/h2>\n<p>La LX3000e est dot\u00e9e d&rsquo;un tout nouveau syst\u00e8me d&rsquo;encre \u00e0 r\u00e9servoir et d&rsquo;une nouvelle t\u00eate d&rsquo;impression qui offre le co\u00fbt le plus bas par impression. L&rsquo;imprimante offre les m\u00eames caract\u00e9ristiques de qualit\u00e9 que la LX910e, avec en plus une t\u00eate d&rsquo;impression rempla\u00e7able par l&rsquo;utilisateur et de grands r\u00e9servoirs d&rsquo;encre CMJ individuels avec de l&rsquo;encre \u00e0 colorant ou \u00e0 pigment. Elle est parfaite pour toute une s\u00e9rie d&rsquo;industries, notamment celles de la sant\u00e9 et de la beaut\u00e9, de l&rsquo;alimentation et des boissons, des produits chimiques, etc.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/dtm-print.eu\/media\/lx3000e\/450-lx3000e-dtm.png\" alt=\"Imprimante d'\u00e9tiquettes couleur LX3000e\" class=\"imageleft\" \/><\/p>\n<h2>R\u00e9servoirs d&rsquo;encre CMJ avec Big Ink\u2122<\/h2>\n<p>Le syst\u00e8me Big Ink utilise des encres \u00e0 colorant ou \u00e0 pigment optimis\u00e9es pour la luminosit\u00e9, la durabilit\u00e9 et la densit\u00e9 optique. Cette derni\u00e8re est particuli\u00e8rement \u00e9lev\u00e9e pour le noir de traitement, ce qui donne le noir le plus noir jamais sorti dans une imprimante CMJ. Elle pr\u00e9sente de nombreux avantages pour les \u00e9tiquettes par rapport aux encres noires de carbone utilis\u00e9es par d&rsquo;autres imprimantes d&rsquo;\u00e9tiquettes en couleur, comme une meilleure r\u00e9sistance \u00e0 l&rsquo;eau, une compatibilit\u00e9 avec une plus large gamme de supports d&rsquo;\u00e9tiquettes sp\u00e9ciaux et une meilleure r\u00e9sistance aux taches.<\/p>\n<div class=\"clear-fix\"><\/div>\n<hr \/>\n<p><img decoding=\"async\" src=\"https:\/\/dtm-print.eu\/media\/lx3000e\/450-lx3000e-logo-fr.jpg\" alt=\"Imprimante d'\u00e9tiquettes couleur LX3000e\" class=\"imageright\" \/><\/p>\n<h2 id=\"feat\">Caract\u00e9ristiques<\/h2>\n<ul class=\"red-triangle\">\n<li><strong>Vitesse d&rsquo;impression rapide<\/strong><span>\u00a0<\/span>\u2013 Avec une vitesse d&rsquo;impression allant jusqu&rsquo;\u00e0 114\u00a0mm (4,5&Prime;) par seconde, vos \u00e9tiquettes seront produites rapidement et efficacement.<\/li>\n<li><strong>Meilleure qualit\u00e9 d&rsquo;impression<\/strong><span>\u00a0<\/span>\u2013 Impression en quadrichromie \u00e0 4800 ppp, 16,7 millions de couleurs.<\/li>\n<li><strong>R\u00e9servoirs d&rsquo;encre individuels<\/strong><span>\u00a0<\/span>\u2013 La toute nouvelle technologie d&rsquo;encre tr\u00e8s avanc\u00e9e utilis\u00e9e par la LX3000e est unique dans le secteur. Elle est dot\u00e9e d&rsquo;une t\u00eate d&rsquo;impression pr\u00e9amorc\u00e9e r\u00e9utilisable aliment\u00e9e par des tubes provenant de trois grands r\u00e9servoirs d&rsquo;encre CMJ distincts (3\u00a0x\u00a060\u00a0ml).<\/li>\n<li><strong>Bo\u00eetier m\u00e9tallique robuste<\/strong><span>\u00a0<\/span>\u2013 La LX3000e est \u00e9quip\u00e9e d&rsquo;un bo\u00eetier m\u00e9tallique \u00e0 rev\u00eatement granit\u00e9, certifi\u00e9 depuis de nombreuses ann\u00e9es dans des zones soumises \u00e0 des r\u00e9glementations de s\u00e9curit\u00e9 plus strictes. Il est particuli\u00e8rement adapt\u00e9 \u00e0 une utilisation dans le domaine de la construction de machines et d&rsquo;installations, ou lorsqu&rsquo;un blindage \u00e9lectromagn\u00e9tique (EMC) est requis.<\/li>\n<li><strong>Massicot<\/strong><span>\u00a0<\/span>\u2013 \u00c9quip\u00e9 d&rsquo;un massicot d&rsquo;\u00e9tiquettes int\u00e9gr\u00e9 (style roue \u00e0 pizza)<\/li>\n<li><strong>Connexion<\/strong><span>\u00a0<\/span>\u2013 Ethernet filaire pour la connexion au r\u00e9seau (\u00e0 venir)<\/li>\n<li><strong>Imprimez de grandes \u00e9tiquettes<\/strong><span>\u00a0<\/span>&#8211; jusqu&rsquo;\u00e0 210 mm de large<\/li>\n<\/ul>\n<div class=\"clear-fix\"><\/div>\n<hr \/>\n<p>&nbsp;<\/p>\n<div class=\"video-container-wrapper\">\n<div class=\"video-container\"><iframe src=\"https:\/\/www.youtube.com\/embed\/9_VZHPT7ZOc\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen=\"\"><\/iframe><\/div>\n<p><em>Imprimer avec l&rsquo;imprimante d&rsquo;\u00e9tiquettes couleur LX3000e<\/em><\/p>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb1px|||||\u00a0\u00bb border_width_all=\u00a0\u00bb2px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1><span style=\"color: #0000ff;\"><strong><\/strong><\/span><\/h1>\n<h1><span style=\"color: #0000ff;\"><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Choix et Prix (indicatif) :\u00a0<\/strong><\/span><span style=\"color: #0000ff;\"><strong><\/strong><\/span><\/h1>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/avdmsolutions.ch\/wp-content\/uploads\/2022\/08\/DTM_PRIMERA_PL_v.4.22-Liste-de-prix-LX3000e.jpg\u00a0\u00bb _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_text=\u00a0\u00bbDTM_PRIMERA_PL_v.4.22 Liste de prix-LX3000e\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_image][et_pb_code _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_button button_text=\u00a0\u00bbSp\u00e9cifications\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][et_pb_button button_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiaG9tZV91cmwiLCJzZXR0aW5ncyI6e319@\u00a0\u00bb button_text=\u00a0\u00bbHOME\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _dynamic_attributes=\u00a0\u00bbbutton_url\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb528.5px\u00a0\u00bb border_radii=\u00a0\u00bbon|6px|6px|6px|6px\u00a0\u00bb border_width_all=\u00a0\u00bb3px\u00a0\u00bb border_color_all=\u00a0\u00bb#000000&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb503.9px\u00a0\u00bb border_radii=\u00a0\u00bbon|5px|5px|5px|5px\u00a0\u00bb border_color_all=\u00a0\u00bb#000000&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_contact_form title=\u00a0\u00bbCe produit vous interresse ? faites nous votre demande : \u00a0\u00bb success_message=\u00a0\u00bbVotre message a \u00e9t\u00e9 envoy\u00e9 avec succes ! merci\u00a0\u00bb _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb _unique_id=\u00a0\u00bb3ba3422c-256a-442a-98db-d063054aea90&Prime; title_font=\u00a0\u00bbCambo||||||||\u00a0\u00bb title_text_color=\u00a0\u00bb#0C71C3&Prime; title_font_size=\u00a0\u00bb36px\u00a0\u00bb captcha_text_color=\u00a0\u00bb#0C71C3&Prime; min_height=\u00a0\u00bb437.1px\u00a0\u00bb border_radii=\u00a0\u00bbon|2px|2px|2px|2px\u00a0\u00bb border_width_all=\u00a0\u00bb6px\u00a0\u00bb border_color_all=\u00a0\u00bb#0C71C3&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_contact_field field_id=\u00a0\u00bbName\u00a0\u00bb field_title=\u00a0\u00bbNom : \u00a0\u00bb conditional_logic=\u00a0\u00bbon\u00a0\u00bb conditional_logic_rules=\u00a0\u00bb%91{%22field%22:%22telephone%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22email%22,%22condition%22:%22contains%22,%22value%22:%22@%22}%93&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbtelephone\u00a0\u00bb field_title=\u00a0\u00bbTelephone : \u00a0\u00bb fullwidth_field=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbEmail\u00a0\u00bb field_title=\u00a0\u00bbAdresse e-mail : \u00a0\u00bb field_type=\u00a0\u00bbemail\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbMessage\u00a0\u00bb field_title=\u00a0\u00bbMessage : \u00a0\u00bb field_type=\u00a0\u00bbtext\u00a0\u00bb fullwidth_field=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imprimante d&rsquo;\u00e9tiquettes couleur LX3000e Le tout nouveau syst\u00e8me Big Ink\u2122 permet de r\u00e9duire les co\u00fbts par \u00e9tiquette avec une vitesse et une qualit\u00e9 d&rsquo;impression exceptionnelles. La LX3000e est dot\u00e9e d&rsquo;un tout nouveau syst\u00e8me d&rsquo;encre \u00e0 r\u00e9servoir et d&rsquo;une nouvelle t\u00eate d&rsquo;impression qui offre le co\u00fbt le plus bas par impression. L&rsquo;imprimante offre les m\u00eames&#8230;<\/p>","protected":false},"author":1,"featured_media":30653,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[36],"tags":[],"class_list":{"0":"post-30652","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-imprimantes-couleurs","9":"post-with-thumbnail","10":"post-with-thumbnail-large"},"_links":{"self":[{"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/posts\/30652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/comments?post=30652"}],"version-history":[{"count":7,"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/posts\/30652\/revisions"}],"predecessor-version":[{"id":30909,"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/posts\/30652\/revisions\/30909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/media\/30653"}],"wp:attachment":[{"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/media?parent=30652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/categories?post=30652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/tags?post=30652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}