{"id":30685,"date":"2022-08-16T11:00:39","date_gmt":"2022-08-16T09:00:39","guid":{"rendered":"https:\/\/avdmsolutions.ch\/?p=30685"},"modified":"2022-08-25T09:28:16","modified_gmt":"2022-08-25T07:28:16","slug":"imprimantes-oki-pro-1050","status":"publish","type":"post","link":"https:\/\/avdmsolutions.re\/en\/imprimantes-oki-pro-1050\/","title":{"rendered":"Imprimantes OKI Pro 1050"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; module_id=\u00a0\u00bb%91table id=2 \/%93&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb443.2px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>La Pro1050 est facile \u00e0 installer en quelques minutes et n\u00e9cessite une formation minimale pour utiliser toute la flexibilit\u00e9 de configuration. Pour simplifier la mise en oeuvre, DTM Print propose une solution compl\u00e8te avec un PC tout-en-un, approuv\u00e9 pour une utilisation 24h\/24 et 7j\/7.<\/p>\n<div class=\"imageright\">\n<p><img decoding=\"async\" src=\"https:\/\/dtm-print.eu\/media\/oki-pro1050\/450-label-raspberry.jpg\" alt=\"OKI Pro1050 Imprimante d'\u00e9tiquettes cinq couleurs\" title=\"\u00e9tiquette cinq couleurs OKI Pro 1050\" class=\"imageright\" \/><\/p>\n<p class=\"center\"><em>\u00e9tiquettes imprim\u00e9es en blanc et en couleur sur papier DTM noir mat<\/em><\/p>\n<\/div>\n<p><strong>Avec la Pro1050, vous entrez dans une nouvelle \u00e8re de l&rsquo;impression d&rsquo;\u00e9tiquettes \u00e0 la demande.<\/strong><\/p>\n<p>Imprimez une ou plusieurs milliers d&rsquo;\u00e9tiquettes \u00e0 la fois, \u00e0 la demande, avec des donn\u00e9es identiques ou uniques sur chaque \u00e9tiquette. Ouvrez de nouveaux march\u00e9s et laissez votre entreprise cro\u00eetre en gagnant de nouveaux clients avec des \u00e9tiquettes qui se dinstingueront de la masse.<\/p>\n<h2>Caract\u00e9ristiques exceptionnelles<\/h2>\n<p><strong>\u00c9tiquettes avec impact.<\/strong><span>\u00a0<\/span>Avec la cinqui\u00e8me couleur blanche, le Pro1050 permet une plus grande flexibilit\u00e9 dans la conception de vos \u00e9tiquettes. Imprimez en blanc seulement ou en blanc avec des couleurs sur des \u00e9tiquettes transparentes ou color\u00e9es\u00a0: Indispensable pour des designs exceptionnels ! DTM offre une vari\u00e9t\u00e9 d&rsquo;\u00e9tiquettes toner sec allant des papiers mats et brillants aux films polyester transparents, jusqu&rsquo;aux rev\u00eatements sp\u00e9ciaux tels que textur\u00e9s ou argent\u00e9s, or, noir et autres mat\u00e9riaux color\u00e9s. Il n&rsquo;y a litt\u00e9ralement aucune limite, quel qe soit votre souhait, votre stock d&rsquo;\u00e9tiquettes vous attend. Vos projets sont uniques et les \u00e9tiquettes le sont aussi !<\/p>\n<p><strong>Pr\u00eat, par\u00e9, imprimez.<\/strong><span>\u00a0<\/span>Un fonctionnement fiable ne devrait pas \u00eatre une exception. C&rsquo;est pourquoi DTM inclut un PC Tout-en-Un pr\u00e9install\u00e9 sur demande avec chaque OKI Pro1050, ce qui vous donne plus de temps pour vos clients et votre production.<\/p>\n<p><strong>Configurez les travaux en quelques minutes.<\/strong><span>\u00a0<\/span>Choisir NiceLabel Free (DTM Edition) pour la cr\u00e9ation simple d&rsquo;\u00e9tiquettes ou la mise \u00e0 jour pour l&rsquo;importation et l&rsquo;impression de donn\u00e9es variables. L\u2018imprimnate peut \u00e9galement \u00eatre utilis\u00e9e avec d&rsquo;autres logiciels de conception d&rsquo;\u00e9tiquettes populaires tels que BarTender et des logiciels graphiques tels que Adobe Illustrator. Imprimer des PDF ? Pour plus de facilit\u00e9, vous pouvez imprimer directement \u00e0 partir d&rsquo;Acrobat Reader.<\/p>\n<p><strong>Qu&rsquo;est-ce que la technologie LED ?<\/strong><span>\u00a0<\/span>Le processus d&rsquo;impression est similaire \u00e0 celui des imprimantes laser, le toner sec \u00e9tant fusionn\u00e9 au mat\u00e9riau de l&rsquo;\u00e9tiquette par une unit\u00e9 thermique (unit\u00e9 de fusion). La technologie LED num\u00e9rique OKI offre une impression haute r\u00e9solution avec des \u00e9tiquettes imprim\u00e9es plus pr\u00e9cises et plus frappantes. La technologie num\u00e9rique \u00e0 LED n\u00e9cessite moins d&rsquo;espace, de sorte que les l\u2018imprimante est compacte, respectueuse de l&rsquo;environnement et \u00e9co-\u00e9nerg\u00e9tiques, utilisant beaucoup moins de mati\u00e8res premi\u00e8res dans le processus de fabrication et consommant moins d&rsquo;\u00e9nergie. Les t\u00eates d&rsquo;impression LED n&rsquo;ont pas de pi\u00e8ces mobiles, ce qui les rend robustes et ultra fiables.<\/p>\n<div class=\"clear-fix\"><\/div>\n<div class=\"video-container-wrapper\">\n<div class=\"video-container\"><iframe src=\"https:\/\/www.youtube.com\/embed\/fXbGNgF737M?rel=0\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen=\"\"><\/iframe><\/div>\n<p><em>OKI Pro1050 Imprimante d&rsquo;\u00e9tiquettes cinq couleurs &#8211; Vid\u00e9o produit<\/em><\/p>\n<\/div>\n<hr \/>\n<h2>Imprimante d&rsquo;\u00e9tiquettes couleur Pro1040 &#8211; 4 couleurs CMYK<\/h2>\n<p>L&rsquo;imprimante d&rsquo;\u00e9tiquettes couleur Pro1040 offre une impression professionnelle en quatre couleurs de format \u00e9troit sur une gamme diff\u00e9rents supports d&rsquo;\u00e9tiquettes fournis par DTM Print. La Pro1040 est id\u00e9ale pour les moyens et grands tirages et fournit des \u00e9tiquettes couleur de haute qualit\u00e9 \u00e0 la demande, sans qu&rsquo;il soit n\u00e9cessaire d&rsquo;acheter des \u00e9tiquettes pr\u00e9-imprim\u00e9es. Id\u00e9alement adapt\u00e9e aux propri\u00e9taires de marques et aux imprimeries, l&rsquo;imprimante d&rsquo;\u00e9tiquettes couleur Pro1040 est con\u00e7ue pour imprimer n&rsquo;importe quelle quantit\u00e9, d&rsquo;une seule \u00e9tiquette \u00e0 plusieurs milliers. N&rsquo;imprimez que ce dont vous avez besoin, ce qui r\u00e9duit le gaspillage et vous fait gagner un temps pr\u00e9cieux et du budget. Sans option de couleur blanche, mais avec la m\u00eame impression couleur haute d\u00e9finition et la m\u00eame technologie LED num\u00e9rique que la Pro1050 d&rsquo;OKI, la Pro1040 donne vie \u00e0 l&rsquo;impression cr\u00e9ative avec des couleurs vives et une sortie de haute qualit\u00e9 \u00e0 1200 dpi.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb1px|||||\u00a0\u00bb border_width_all=\u00a0\u00bb2px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1><span style=\"color: #0000ff;\"><strong><\/strong><\/span><\/h1>\n<h1><span style=\"color: #0000ff;\"><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Choix et Prix (indicatif) :\u00a0<\/strong><\/span><span style=\"color: #0000ff;\"><strong><\/strong><\/span><\/h1>\n<p>[\/et_pb_text][et_pb_code _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;]\n<table id=\"tablepress-100\" class=\"tablepress tablepress-id-100\">\n<thead>\n<tr class=\"row-1\">\n\t<th colspan=\"3\" class=\"column-1\">Merci de nous consulter<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<\/tbody>\n<\/table>\n<!-- #tablepress-100 from cache -->[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_button button_text=\u00a0\u00bbSp\u00e9cifications\u00a0\u00bb _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][et_pb_button button_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiaG9tZV91cmwiLCJzZXR0aW5ncyI6e319@\u00a0\u00bb button_text=\u00a0\u00bbHOME\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _dynamic_attributes=\u00a0\u00bbbutton_url\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; custom_margin=\u00a0\u00bb||-16px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb528.5px\u00a0\u00bb border_radii=\u00a0\u00bbon|6px|6px|6px|6px\u00a0\u00bb border_width_all=\u00a0\u00bb3px\u00a0\u00bb border_color_all=\u00a0\u00bb#000000&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb503.9px\u00a0\u00bb border_radii=\u00a0\u00bbon|5px|5px|5px|5px\u00a0\u00bb border_color_all=\u00a0\u00bb#000000&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_contact_form title=\u00a0\u00bbCe produit vous interresse ? faites nous votre demande : \u00a0\u00bb success_message=\u00a0\u00bbVotre message a \u00e9t\u00e9 envoy\u00e9 avec succes ! merci\u00a0\u00bb _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb _unique_id=\u00a0\u00bb3ba3422c-256a-442a-98db-d063054aea90&Prime; title_font=\u00a0\u00bbCambo||||||||\u00a0\u00bb title_text_color=\u00a0\u00bb#0C71C3&Prime; title_font_size=\u00a0\u00bb36px\u00a0\u00bb captcha_text_color=\u00a0\u00bb#0C71C3&Prime; min_height=\u00a0\u00bb437.1px\u00a0\u00bb border_radii=\u00a0\u00bbon|2px|2px|2px|2px\u00a0\u00bb border_width_all=\u00a0\u00bb6px\u00a0\u00bb border_color_all=\u00a0\u00bb#0C71C3&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_contact_field field_id=\u00a0\u00bbName\u00a0\u00bb field_title=\u00a0\u00bbNom : \u00a0\u00bb conditional_logic=\u00a0\u00bbon\u00a0\u00bb conditional_logic_rules=\u00a0\u00bb%91{%22field%22:%22telephone%22,%22condition%22:%22is not empty%22,%22value%22:%22%22},{%22field%22:%22email%22,%22condition%22:%22contains%22,%22value%22:%22@%22}%93&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbtelephone\u00a0\u00bb field_title=\u00a0\u00bbTelephone : \u00a0\u00bb fullwidth_field=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbEmail\u00a0\u00bb field_title=\u00a0\u00bbAdresse e-mail : \u00a0\u00bb field_type=\u00a0\u00bbemail\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbMessage\u00a0\u00bb field_title=\u00a0\u00bbMessage : \u00a0\u00bb field_type=\u00a0\u00bbtext\u00a0\u00bb fullwidth_field=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Pro1050 est facile \u00e0 installer en quelques minutes et n\u00e9cessite une formation minimale pour utiliser toute la flexibilit\u00e9 de configuration. Pour simplifier la mise en oeuvre, DTM Print propose une solution compl\u00e8te avec un PC tout-en-un, approuv\u00e9 pour une utilisation 24h\/24 et 7j\/7. \u00e9tiquettes imprim\u00e9es en blanc et en couleur sur papier DTM&#8230;<\/p>","protected":false},"author":1,"featured_media":30810,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[36],"tags":[],"class_list":{"0":"post-30685","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-imprimantes-couleurs","9":"post-with-thumbnail","10":"post-with-thumbnail-large"},"_links":{"self":[{"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/posts\/30685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/comments?post=30685"}],"version-history":[{"count":6,"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/posts\/30685\/revisions"}],"predecessor-version":[{"id":30952,"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/posts\/30685\/revisions\/30952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/media\/30810"}],"wp:attachment":[{"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/media?parent=30685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/categories?post=30685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/avdmsolutions.re\/en\/wp-json\/wp\/v2\/tags?post=30685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}